{"id":21785,"date":"2023-05-30T11:25:24","date_gmt":"2023-05-30T11:25:24","guid":{"rendered":"https:\/\/emea.dev.technetix.com\/unkategorisiert\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/"},"modified":"2023-06-06T08:00:47","modified_gmt":"2023-06-06T08:00:47","slug":"technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika","status":"publish","type":"post","link":"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/","title":{"rendered":"Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika"},"content":{"rendered":"<p><strong>Albourne, Vereinigtes K\u00f6nigreich \u2212 Dienstag, den 30. Mai 2023<\/strong> \u2212 Technetix Group Ltd, der weltweit f\u00fchrende Hersteller von Breitbandtechnologie, ist erfreut, die Ernennung von Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika bekanntgeben zu d\u00fcrfen.<br\/><br\/>Hernan ist ein anerkannter Experte mit mehr als 28 Jahren Erfahrung im Kabel-TV-Markt. Urspr\u00fcnglich aus Santagio, Chile, kommend verf\u00fcgt er \u00fcber einen Abschluss der Universit\u00e4t T\u00e9cnica Federico Santa Maria im Bereich Elektrotechnik sowie ein Postgraduiertendiplom der UCLA im Bereich Netzwerktechnologie. Hernan ist seit dem Jahr 1995 Mitglied der SCTE.<br\/><br\/>\u201eHernan hatte bei der technologischen Entwicklung des Kabel-TV-Markts in S\u00fcdamerika eine zentrale Rolle inne und ich bin sehr erfreut, ihn im CTO-Team von Technetix begr\u00fc\u00dfen zu d\u00fcrfen\u201c, kommentierte Jan Ariesen, Group Chief Technology Officer.<br\/><br\/>W\u00e4hrend seiner gesamten Karriere hat Hernan die lateinamerikanischen Netzbetreiber bei deren \u00dcbergang von reinen TV-Anbietern zu vollwertigen Telco-Unternehmen unterst\u00fctzt. So war er auch bei signifikanten Wegpunkten wie dem ersten Start von Festnetz-Telefonie-\u00fcber-Kabel-Diensten in den Americas, dem ersten Einsatz von DOCSIS-Diensten in Lateinamerika und der Innovation und Evolution von der analogen Welt zur digitalen HD-Welt sowie erst k\u00fcrzlich zu IPTV-Diensten in mehreren lateinamerikanischen und karibischen L\u00e4ndern involviert. Als Senior Engineering Director f\u00fcr Liberty Latin America und VTR nahm er eine wesentliche Rolle bei der Etablierung technologischer Ende-zu-Ende-Strategien f\u00fcr Access-Netzwerke und Dienste ein. Hernan genie\u00dft aufgrund seiner au\u00dferordentlichen Arbeitsethik sowie seiner Liebe zum Detail gro\u00dfe Anerkennung.<br\/><br\/>Hernan sagte: \u201eIch f\u00fchle mich geehrt, nun zum Technetix-Team zu geh\u00f6ren, und werde sehr gerne meine Erfahrung einbringen. Ich freue mich darauf, mit Kompetenz, Leidenschaft und Engagement zum weiteren Wachstum des Kabelmarkts beitragen zu d\u00fcrfen\u201c.<\/p>","protected":false},"excerpt":{"rendered":"<p>Albourne, Vereinigtes K\u00f6nigreich \u2212 Dienstag, den 30. Mai 2023 \u2212 Technetix Group Ltd, der weltweit f\u00fchrende Hersteller von Breitbandtechnologie, ist erfreut, die Ernennung von Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika bekanntgeben zu d\u00fcrfen. Hernan ist ein anerkannter Experte mit mehr als 28 Jahren Erfahrung im Kabel-TV-Markt. Urspr\u00fcnglich aus Santagio, Chile, kommend &#8230; <a title=\"Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika\" class=\"read-more\" href=\"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/\" aria-label=\"Mehr zu Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"categories":[84],"tags":[85],"class_list":["post-21785","post","type-post","status-publish","format-standard","hentry","category-neuigkeiten","tag-emea-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.5 (Yoast SEO v23.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika - Technetix EMEA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika - Technetix EMEA\" \/>\n<meta property=\"og:description\" content=\"Albourne, Vereinigtes K\u00f6nigreich \u2212 Dienstag, den 30. Mai 2023 \u2212 Technetix Group Ltd, der weltweit f\u00fchrende Hersteller von Breitbandtechnologie, ist erfreut, die Ernennung von Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika bekanntgeben zu d\u00fcrfen. Hernan ist ein anerkannter Experte mit mehr als 28 Jahren Erfahrung im Kabel-TV-Markt. Urspr\u00fcnglich aus Santagio, Chile, kommend ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/\" \/>\n<meta property=\"og:site_name\" content=\"Technetix EMEA\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-30T11:25:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-06T08:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/emea.dev.technetix.com\/wp-content\/uploads\/sites\/2\/2023\/06\/logo-Technetix-1200x675-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@technetixgroup\" \/>\n<meta name=\"twitter:site\" content=\"@technetixgroup\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika\",\"datePublished\":\"2023-05-30T11:25:24+00:00\",\"dateModified\":\"2023-06-06T08:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/\"},\"wordCount\":292,\"publisher\":{\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/#organization\"},\"keywords\":[\"EMEA\"],\"articleSection\":[\"Neuigkeiten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/\",\"url\":\"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/\",\"name\":\"Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika - Technetix EMEA\",\"isPartOf\":{\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/#website\"},\"datePublished\":\"2023-05-30T11:25:24+00:00\",\"dateModified\":\"2023-06-06T08:00:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/emea.dev.technetix.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unkategorisiert\",\"item\":\"https:\/\/emea.dev.technetix.com\/de\/blog\/unkategorisiert\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/#website\",\"url\":\"https:\/\/emea.dev.technetix.com\/de\/\",\"name\":\"Technetix\",\"description\":\"Next-generation broadband equipment engineering\",\"publisher\":{\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/emea.dev.technetix.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/#organization\",\"name\":\"Technetix\",\"url\":\"https:\/\/emea.dev.technetix.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/emea.dev.technetix.com\/wp-content\/uploads\/sites\/2\/2023\/06\/logo-Technetix-1000x1000-1.png\",\"contentUrl\":\"https:\/\/emea.dev.technetix.com\/wp-content\/uploads\/sites\/2\/2023\/06\/logo-Technetix-1000x1000-1.png\",\"width\":1000,\"height\":1000,\"caption\":\"Technetix\"},\"image\":{\"@id\":\"https:\/\/emea.dev.technetix.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/technetixgroup\",\"https:\/\/www.linkedin.com\/company\/technetix\/\",\"https:\/\/www.youtube.com\/c\/Technetix-group\"]},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika - Technetix EMEA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/","og_locale":"de_DE","og_type":"article","og_title":"Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika - Technetix EMEA","og_description":"Albourne, Vereinigtes K\u00f6nigreich \u2212 Dienstag, den 30. Mai 2023 \u2212 Technetix Group Ltd, der weltweit f\u00fchrende Hersteller von Breitbandtechnologie, ist erfreut, die Ernennung von Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika bekanntgeben zu d\u00fcrfen. Hernan ist ein anerkannter Experte mit mehr als 28 Jahren Erfahrung im Kabel-TV-Markt. Urspr\u00fcnglich aus Santagio, Chile, kommend ... Read more","og_url":"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/","og_site_name":"Technetix EMEA","article_published_time":"2023-05-30T11:25:24+00:00","article_modified_time":"2023-06-06T08:00:47+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/emea.dev.technetix.com\/wp-content\/uploads\/sites\/2\/2023\/06\/logo-Technetix-1200x675-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@technetixgroup","twitter_site":"@technetixgroup","twitter_misc":{"Verfasst von":"","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/#article","isPartOf":{"@id":"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/"},"author":{"name":"","@id":""},"headline":"Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika","datePublished":"2023-05-30T11:25:24+00:00","dateModified":"2023-06-06T08:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/"},"wordCount":292,"publisher":{"@id":"https:\/\/emea.dev.technetix.com\/de\/#organization"},"keywords":["EMEA"],"articleSection":["Neuigkeiten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/","url":"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/","name":"Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika - Technetix EMEA","isPartOf":{"@id":"https:\/\/emea.dev.technetix.com\/de\/#website"},"datePublished":"2023-05-30T11:25:24+00:00","dateModified":"2023-06-06T08:00:47+00:00","breadcrumb":{"@id":"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/emea.dev.technetix.com\/de\/neuigkeiten\/technetix-ernennt-hernan-benavides-zum-chief-technology-officer-fuer-die-region-suedamerika\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/emea.dev.technetix.com\/de\/"},{"@type":"ListItem","position":2,"name":"Unkategorisiert","item":"https:\/\/emea.dev.technetix.com\/de\/blog\/unkategorisiert\/"},{"@type":"ListItem","position":3,"name":"Technetix ernennt Hernan Benavides zum Chief Technology Officer f\u00fcr die Region S\u00fcdamerika"}]},{"@type":"WebSite","@id":"https:\/\/emea.dev.technetix.com\/de\/#website","url":"https:\/\/emea.dev.technetix.com\/de\/","name":"Technetix","description":"Next-generation broadband equipment engineering","publisher":{"@id":"https:\/\/emea.dev.technetix.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emea.dev.technetix.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/emea.dev.technetix.com\/de\/#organization","name":"Technetix","url":"https:\/\/emea.dev.technetix.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/emea.dev.technetix.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/emea.dev.technetix.com\/wp-content\/uploads\/sites\/2\/2023\/06\/logo-Technetix-1000x1000-1.png","contentUrl":"https:\/\/emea.dev.technetix.com\/wp-content\/uploads\/sites\/2\/2023\/06\/logo-Technetix-1000x1000-1.png","width":1000,"height":1000,"caption":"Technetix"},"image":{"@id":"https:\/\/emea.dev.technetix.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/technetixgroup","https:\/\/www.linkedin.com\/company\/technetix\/","https:\/\/www.youtube.com\/c\/Technetix-group"]},{"@type":"Person","@id":""}]}},"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-14 22:44:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/emea.dev.technetix.com\/de\/wp-json\/wp\/v2\/posts\/21785"}],"collection":[{"href":"https:\/\/emea.dev.technetix.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emea.dev.technetix.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emea.dev.technetix.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/emea.dev.technetix.com\/de\/wp-json\/wp\/v2\/comments?post=21785"}],"version-history":[{"count":1,"href":"https:\/\/emea.dev.technetix.com\/de\/wp-json\/wp\/v2\/posts\/21785\/revisions"}],"predecessor-version":[{"id":21786,"href":"https:\/\/emea.dev.technetix.com\/de\/wp-json\/wp\/v2\/posts\/21785\/revisions\/21786"}],"wp:attachment":[{"href":"https:\/\/emea.dev.technetix.com\/de\/wp-json\/wp\/v2\/media?parent=21785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emea.dev.technetix.com\/de\/wp-json\/wp\/v2\/categories?post=21785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emea.dev.technetix.com\/de\/wp-json\/wp\/v2\/tags?post=21785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}